{"id":1,"date":"2018-11-08T19:56:12","date_gmt":"2018-11-08T18:56:12","guid":{"rendered":"https:\/\/vernissage.me\/?p=1"},"modified":"2018-11-08T19:56:12","modified_gmt":"2018-11-08T18:56:12","slug":"hallo-welt","status":"publish","type":"post","link":"https:\/\/vernissage.me\/de\/2018\/11\/08\/hallo-welt\/","title":{"rendered":"Hallo Welt!"},"content":{"rendered":"<p>Willkommen zur deutschen Version von WordPress. Dies ist der erste Beitrag. Du kannst ihn bearbeiten oder l\u00f6schen. Und dann starte mit dem Schreiben!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen zur deutschen Version von WordPress. Dies ist der erste Beitrag. Du kannst ihn bearbeiten oder l\u00f6schen. Und dann starte mit dem Schreiben!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/posts\/1"}],"collection":[{"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":0,"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"wp:attachment":[{"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vernissage.me\/de\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}